{"id":886,"date":"2026-04-02T11:58:31","date_gmt":"2026-04-02T11:58:31","guid":{"rendered":"https:\/\/nordicinternetsolutions.com\/?page_id=886"},"modified":"2026-04-16T16:54:21","modified_gmt":"2026-04-16T16:54:21","slug":"prijzen-3","status":"publish","type":"page","link":"https:\/\/nordicinternetsolutions.com\/nl\/prices-3\/","title":{"rendered":"prijzen"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section\"><span class=\"et-pb-background-video\"><\/span>\n<div class=\"et_pb_row_0 et_pb_row et-vb-row--no-module et_flex_row\">\n<div class=\"et_pb_column_0 et_pb_column et-last-child et_flex_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\"><\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_block_row et_animated\">\n<div class=\"et_pb_column_1 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h1>prijzen IT-oplossingen<\/h1>\n<p>\u00a0<\/p>\n<\/div>\n<div class=\"et_pb_icon_0 et_pb_icon et_pb_module et_flex_module\"><span class=\"et_pb_icon_wrap\" data-icon=\"Z\"><span class=\"et-pb-icon\">Z<\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_2 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_2 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_animated et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><h1 style=\"text-align: center;\">Stabiel, veilig en betrouwbaar.<\/h1>\n<h1 style=\"text-align: center;\">Kies een van de onderstaande pakketten die bij u past.<\/h1>\n<h1 style=\"text-align: center;\">Als u een andere oplossing wenst, kunt u ons e-mailen.<\/h1>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section dy-pricing-table-25\">\n<div class=\"et_pb_row_3 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_3 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_code_0 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><div class=\"dy-toggle dy-toggle-s25\">\n  <span class=\"dy-toggle__left-text-s25\">Maandelijks<\/span> <!-- Change the LEFT text here -->\n  <input type=\"checkbox\" id=\"dy-toggle__input-s25\">\n  <label for=\"dy-toggle__input-s25\"><\/label>\n  <span class=\"dy-toggle__right-text-s25\">Jaarlijks<\/span> <!-- Change the RIGHT text here -->\n<\/div>\n<\/div><\/div>\n\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><p>Bespaar tot 600,00 SEK<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_code_1 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><style>\n  .section--hidden {\ndisplay: none!important;  \n} \n  \n  .dy-toggle-s25 {\n    position:relative;\n    display:inline-block;\n    width:58px;\n    height:22px;\n  } \n \n  .dy-toggle__left-text-s25 {\n    position:absolute;\n    top:50%;\n    left:-68px;\/* Change the LEFT text left shift relative to center point here *\/\n    font-family: 'Open Sans',Helvetica,Arial,Lucida,sans-serif;\/* Change the LEFT text font-family here *\/ \n    font-size:14px;\/* Change the LEFT text font size here *\/ \n    font-weight: 500;\/* Change the LEFT text font weight here *\/ \n    transform:translateY(-50%);\n    color: #ffffff;\/* Change the LEFT text color here *\/  \n  }\n  \n  .dy-toggle-s25 input {\n    display: none;\n  }\n  \n  .dy-toggle__right-text-s25 {\n    position:absolute;\n    top:50%;\n    right:-50px;\/* Change the RIGHT text right shift relative to center point here *\/ \n    font-family: 'Open Sans',Helvetica,Arial,Lucida,sans-serif;\/* Change the RIGHT text font-family here *\/ \n    font-size:14px;\/* Change the RIGHT text font size here *\/ \n    font-weight: 500;\/* Change the RIGHT text font weight here *\/ \n    transform:translateY(-50%);\n    color: #ffffff;\/* Change the RIGHT text color here *\/ \n  }\n\n\n  .dy-toggle-s25 label {\n    position:absolute;\n    top:0;\n    left:0;\n    right:0;\n    bottom:0;   \n    cursor:pointer;\n    border-radius: 36px;    \n    transition: background-image 0.3s;\nbackground-image: linear-gradient(135deg, #146641 0%,#5cff9d 100%); \/* Change toggle's background linear-gradient colors before toggle switching here *\/\n  }\n  .dy-toggle-s25 label::before {\n    content:\"\";\n    position:absolute;\n    top:-3px;\n    left:-3px;\n    width:28px;\n    height:28px;\n    background-color:#fff;\n    border-radius: 50%;\n    transition: transform 0.3s;\n    box-shadow: 0px 2px 18px 0px rgba(0,0,0,0.3);\n  }\n  .dy-toggle-s25 input:checked+label {\n    background-image: linear-gradient(90deg,#999999 0%,#cccccc 100%); \/* Change toggle's background linear-gradient colors after toggle switching here *\/\n  }\n  .dy-toggle-s25 input:checked+label::before {\n    transform: translateX(34px);\n  }\n\n<\/style>\n\n<\/div><\/div>\n\n<div class=\"et_pb_code_2 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><script>\njQuery(document).ready(function($) { \n      $('.dy-toggle-year-s25').addClass('section--hidden');\n});\n\njQuery(document).ready(function($) {\n  $('#dy-toggle__input-s25').change(function() {\n    if ($(this).is(':checked')) {\n      $('.dy-toggle-month-s25').addClass('section--hidden');\n      $('.dy-toggle-year-s25').removeClass('section--hidden');\n    } else {\n      $('.dy-toggle-month-s25').removeClass('section--hidden');\n      $('.dy-toggle-year-s25').addClass('section--hidden');\n    }\n  });\n});\n<\/script>\n\n\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_pb_gutters1 et_block_row dy-toggle-month-s25\">\n<div class=\"et_pb_column_4 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough et_animated\">\n<div class=\"et_pb_divider_0 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: left;\">Brons<\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_left-tablet et_pb_text_align_left-phone\"><div class=\"et_pb_text_inner\"><p><strong>WordPress Hosting<\/strong><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_pricing_tables_0 et_pb_pricing_tables et_pb_pricing clearfix et_pb_pricing_1 et_pb_no_featured_in_first_row et_pb_module et_flex_module\">\n<div class=\"et_pb_pricing_table_0 et_pb_pricing_table et_pb_module et_block_module et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\"><div class=\"et_pb_pricing_heading\"><\/div><div class=\"et_pb_pricing_content_top\"><div class=\"et_pb_et_price\"><span class=\"et_pb_sum\">89 SEK<\/span><span class=\"et_pb_frequency\"><span class=\"et_pb_frequency_slash\">\/<\/span>maand<\/span><\/div><\/div><div class=\"et_pb_pricing_content\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_left et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Maandelijks gefactureerd<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 Domein inbegrepen (.nl \/ .se \/ .nu)<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 SSL-certificaat inbegrepen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_3 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">25 GB webruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_4 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 Postvak<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_5 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">2 GB Mailruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_6 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Wordpress bijwerken<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_7 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Website back-up<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_8 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module preset--module--divi-button--default\" href=\"\/nl\/contact-form-hosting-01\/\">Aan de slag<\/a><\/div>\n\n<div class=\"et_pb_code_3 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><style>\n.dy-pricing-table-25\n.et_pb_blurb_position_left .et_pb_blurb_container {\n    padding-left: 5px;\n}\n@media (max-width: 980px) {\n.dy-pricing-table-25 .et_pb_gutters1 .et_pb_column,\n.dy-pricing-table-25 .et_pb_gutters1.et_pb_row .et_pb_column { \n  margin-bottom: 30px !important;\n}\n\n<\/style><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_5 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough et_animated\">\n<div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3>Populair<\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_1 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3>Zilver<\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><strong>WordPress Hosting<\/strong><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_pricing_tables_1 et_pb_pricing_tables et_pb_pricing clearfix et_pb_pricing_1 et_pb_no_featured_in_first_row et_pb_module et_flex_module\">\n<div class=\"et_pb_pricing_table_1 et_pb_pricing_table et_pb_module et_block_module et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\"><div class=\"et_pb_pricing_heading\"><\/div><div class=\"et_pb_pricing_content_top\"><div class=\"et_pb_et_price\"><span class=\"et_pb_sum\">159 SEK<\/span><span class=\"et_pb_frequency\"><span class=\"et_pb_frequency_slash\">\/<\/span>maand<\/span><\/div><\/div><div class=\"et_pb_pricing_content\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_blurb_9 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Maandelijks gefactureerd<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_10 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 Domein inbegrepen (.nl \/ .se \/ .nu)<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_11 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 SSL-certificaat inbegrepen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_12 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">50 GB webruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_13 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">2 brievenbussen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_14 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">3 GB Mailruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_15 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Wordpress bijwerken<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_16 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Website back-up<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_17 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Webanalyse<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module preset--module--divi-button--default\" href=\"\/nl\/contact-form-hosting-01\/\">Aan de slag<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_6 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough et_animated\">\n<div class=\"et_pb_divider_2 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3><strong>Goud<\/strong><\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><strong>WordPress Hosting<\/strong><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_pricing_tables_2 et_pb_pricing_tables et_pb_pricing clearfix et_pb_pricing_1 et_pb_no_featured_in_first_row et_pb_module et_flex_module\">\n<div class=\"et_pb_pricing_table_2 et_pb_pricing_table et_pb_module et_block_module et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\"><div class=\"et_pb_pricing_heading\"><\/div><div class=\"et_pb_pricing_content_top\"><div class=\"et_pb_et_price\"><span class=\"et_pb_sum\">299 SEK<\/span><span class=\"et_pb_frequency\"><span class=\"et_pb_frequency_slash\">\/<\/span>maand<\/span><\/div><\/div><div class=\"et_pb_pricing_content\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_blurb_18 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Maandelijks gefactureerd<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_19 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 Domein inbegrepen (.nl \/ .se \/ .nu)<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_20 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 SSL-certificaat inbegrepen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_21 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">100 GB webruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_22 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">3 Brievenbussen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_23 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">5 GB Mailspace<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_24 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Wordpress bijwerken<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_25 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Website back-up<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_26 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Webanalyse<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module preset--module--divi-button--default\" href=\"\/nl\/contact-form-hosting-01\/\">Aan de slag<\/a><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_5 et_pb_row et_pb_gutters1 et_block_row dy-toggle-year-s25\">\n<div class=\"et_pb_column_7 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_divider_3 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3>Brons<\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_text_11 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_left-tablet et_pb_text_align_left-phone\"><div class=\"et_pb_text_inner\"><p><strong>WordPress Hosting<\/strong><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_pricing_tables_3 et_pb_pricing_tables et_pb_pricing clearfix et_pb_pricing_1 et_pb_no_featured_in_first_row et_pb_module et_flex_module\">\n<div class=\"et_pb_pricing_table_3 et_pb_pricing_table et_pb_module et_block_module et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\"><div class=\"et_pb_pricing_heading\"><\/div><div class=\"et_pb_pricing_content_top\"><div class=\"et_pb_et_price\"><span class=\"et_pb_sum\">79 SEK<\/span><span class=\"et_pb_frequency\"><span class=\"et_pb_frequency_slash\">\/<\/span>maand<\/span><\/div><\/div><div class=\"et_pb_pricing_content\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_blurb_27 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">948,00 SEK Jaarlijks gefactureerd<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_28 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 Domein inbegrepen (.nl \/ .se \/ .nu)<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_29 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 SSL-certificaat inbegrepen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_30 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">25 GB webruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_31 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 Postvak<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_32 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">2 GB Mailruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_33 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Wordpress bijwerken<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_34 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Website back-up<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_35 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_3_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_3 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module preset--module--divi-button--default\" href=\"\/nl\/contact-form-hosting-02\/\">Aan de slag<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_8 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_12 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3>Populair<\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_divider_4 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_text_13 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3>Zilver<\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_text_14 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><b>WordPress Hosting<\/b><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_pricing_tables_4 et_pb_pricing_tables et_pb_pricing clearfix et_pb_pricing_1 et_pb_no_featured_in_first_row et_pb_module et_flex_module\">\n<div class=\"et_pb_pricing_table_4 et_pb_pricing_table et_pb_module et_block_module et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\"><div class=\"et_pb_pricing_heading\"><\/div><div class=\"et_pb_pricing_content_top\"><div class=\"et_pb_et_price\"><span class=\"et_pb_sum\">109 SEK<\/span><span class=\"et_pb_frequency\"><span class=\"et_pb_frequency_slash\">\/<\/span>maand<\/span><\/div><\/div><div class=\"et_pb_pricing_content\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_blurb_36 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1308,00 SEK Jaarlijks gefactureerd<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_37 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 Domein inbegrepen (.nl \/ .se \/ .nu)<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_38 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 SSL-certificaat inbegrepen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_39 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">50 GB webruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_40 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">2 brievenbussen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_41 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">3 GB Mailruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_42 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Wordpress bijwerken<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_43 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Website back-up<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_44 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Webanalyse<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_4_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_4 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module preset--module--divi-button--default\" href=\"\/nl\/contact-form-hosting-02\/\">Aan de slag<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_9 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_divider_5 et_pb_divider et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\n<div class=\"et_pb_text_15 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3><strong>Goud<\/strong><\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_text_16 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><strong>WordPress Hosting<\/strong><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_pricing_tables_5 et_pb_pricing_tables et_pb_pricing clearfix et_pb_pricing_1 et_pb_no_featured_in_first_row et_pb_module et_flex_module\">\n<div class=\"et_pb_pricing_table_5 et_pb_pricing_table et_pb_module et_block_module et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\"><div class=\"et_pb_pricing_heading\"><\/div><div class=\"et_pb_pricing_content_top\"><div class=\"et_pb_et_price\"><span class=\"et_pb_sum\">249 SEK<\/span><span class=\"et_pb_frequency\"><span class=\"et_pb_frequency_slash\">\/<\/span>maand<\/span><\/div><\/div><div class=\"et_pb_pricing_content\"><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_blurb_45 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">2988,00 SEK Jaarlijks gefactureerd<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_46 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 Domein inbegrepen (.nl \/ .se \/ .nu)<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_47 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">1 SSL-certificaat inbegrepen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_48 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">100 GB webruimte<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_49 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">3 Brievenbussen<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_50 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">5 GB Mailspace<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_51 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Wordpress bijwerken<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_52 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Website back-up<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_53 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Webanalyse<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_5_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_5 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module preset--module--divi-button--default\" href=\"\/nl\/contact-form-hosting-02\/\">Aan de slag<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_3 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_6 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_10 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_17 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><p>Veelgestelde Vragen over websitehosting<\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_6_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_6 et_pb_button et_pb_bg_layout_dark et_pb_module et_flex_module preset--module--divi-button--default\" href=\"\/nl\/faq-3\/\">Klik hier<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-886","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>prices - Nordic Internet Solutions AB | Web Design &amp; Digital Strategy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nordicinternetsolutions.com\/nl\/prijzen-3\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"prices - Nordic Internet Solutions AB | Web Design &amp; Digital Strategy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nordicinternetsolutions.com\/nl\/prijzen-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Nordic Internet Solutions AB | Web Design &amp; Digital Strategy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61585601183693\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T16:54:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/prices-3\\\/\",\"url\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/prices-3\\\/\",\"name\":\"prices - Nordic Internet Solutions AB | Web Design &amp; Digital Strategy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/#website\"},\"datePublished\":\"2026-04-02T11:58:31+00:00\",\"dateModified\":\"2026-04-16T16:54:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/prices-3\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nordicinternetsolutions.com\\\/prices-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/prices-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"prices\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/#website\",\"url\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/\",\"name\":\"Nordic Internet Solutions AB | Web Design & Digital Strategy\",\"description\":\"Your partner for scalable web solutions and Nordic excellence\",\"publisher\":{\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/#organization\",\"name\":\"Nordic Internet Solutions AB | Web Design & Digital Strategy\",\"url\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-Complete-transparant.png\",\"contentUrl\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-Complete-transparant.png\",\"width\":634,\"height\":163,\"caption\":\"Nordic Internet Solutions AB | Web Design & Digital Strategy\"},\"image\":{\"@id\":\"https:\\\/\\\/nordicinternetsolutions.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61585601183693\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"prijzen - Nordic Internet Solutions AB | Webdesign &amp; Digitale Strategie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nordicinternetsolutions.com\/nl\/prijzen-3\/","og_locale":"nl_NL","og_type":"article","og_title":"prices - Nordic Internet Solutions AB | Web Design &amp; Digital Strategy","og_url":"https:\/\/nordicinternetsolutions.com\/nl\/prijzen-3\/","og_site_name":"Nordic Internet Solutions AB | Web Design &amp; Digital Strategy","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61585601183693","article_modified_time":"2026-04-16T16:54:21+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nordicinternetsolutions.com\/prices-3\/","url":"https:\/\/nordicinternetsolutions.com\/prices-3\/","name":"prijzen - Nordic Internet Solutions AB | Webdesign &amp; Digitale Strategie","isPartOf":{"@id":"https:\/\/nordicinternetsolutions.com\/#website"},"datePublished":"2026-04-02T11:58:31+00:00","dateModified":"2026-04-16T16:54:21+00:00","breadcrumb":{"@id":"https:\/\/nordicinternetsolutions.com\/prices-3\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nordicinternetsolutions.com\/prices-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nordicinternetsolutions.com\/prices-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nordicinternetsolutions.com\/"},{"@type":"ListItem","position":2,"name":"prices"}]},{"@type":"WebSite","@id":"https:\/\/nordicinternetsolutions.com\/#website","url":"https:\/\/nordicinternetsolutions.com\/","name":"Nordic Internet Solutions AB | Webdesign &amp; Digitale Strategie","description":"Uw partner voor schaalbare weboplossingen en Noordse excellentie","publisher":{"@id":"https:\/\/nordicinternetsolutions.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nordicinternetsolutions.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/nordicinternetsolutions.com\/#organization","name":"Nordic Internet Solutions AB | Webdesign &amp; Digitale Strategie","url":"https:\/\/nordicinternetsolutions.com\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/nordicinternetsolutions.com\/#\/schema\/logo\/image\/","url":"https:\/\/nordicinternetsolutions.com\/wp-content\/uploads\/2026\/03\/Logo-Complete-transparant.png","contentUrl":"https:\/\/nordicinternetsolutions.com\/wp-content\/uploads\/2026\/03\/Logo-Complete-transparant.png","width":634,"height":163,"caption":"Nordic Internet Solutions AB | Web Design & Digital Strategy"},"image":{"@id":"https:\/\/nordicinternetsolutions.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61585601183693"]}]}},"_links":{"self":[{"href":"https:\/\/nordicinternetsolutions.com\/nl\/wp-json\/wp\/v2\/pages\/886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nordicinternetsolutions.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nordicinternetsolutions.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nordicinternetsolutions.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nordicinternetsolutions.com\/nl\/wp-json\/wp\/v2\/comments?post=886"}],"version-history":[{"count":103,"href":"https:\/\/nordicinternetsolutions.com\/nl\/wp-json\/wp\/v2\/pages\/886\/revisions"}],"predecessor-version":[{"id":224763,"href":"https:\/\/nordicinternetsolutions.com\/nl\/wp-json\/wp\/v2\/pages\/886\/revisions\/224763"}],"wp:attachment":[{"href":"https:\/\/nordicinternetsolutions.com\/nl\/wp-json\/wp\/v2\/media?parent=886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}